{"id":500,"date":"2024-12-29T07:38:41","date_gmt":"2024-12-29T07:38:41","guid":{"rendered":"https:\/\/csmounts.com\/new-csmounts\/?post_type=product&#038;p=500"},"modified":"2025-01-11T06:15:00","modified_gmt":"2025-01-11T06:15:00","slug":"m3d-rkl-kidevo-kiddo","status":"publish","type":"product","link":"https:\/\/csmounts.com\/new-csmounts\/product\/m3d-rkl-kidevo-kiddo\/","title":{"rendered":"M3D RKL Kidevo\/Kiddo"},"content":{"rendered":"<p>Monty 3D frame clamp with sleeves to mount on the Kidevo (Ottobock) and Kiddo (Veldink4kids) wheelchairs with oval frame tubes 50 x 25 mm.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Monty 3D frame clamp with sleeves to mount on the Kidevo (Ottobock) and Kiddo (Veldink4kids) wheelchairs with oval frame tubes 50 x 25 mm.<\/p>\n","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[101,105,50],"product_tag":[],"class_list":["post-500","product","type-product","status-publish","product_cat-aac-device-mounts","product_cat-components-aac-device-mounts","product_cat-components-frame-clamp","first","instock","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>M3D RKL Kidevo\/Kiddo - CS Mounting Systems<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/csmounts.com\/new-csmounts\/product\/m3d-rkl-kidevo-kiddo\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"M3D RKL Kidevo\/Kiddo - CS Mounting Systems\" \/>\n<meta property=\"og:description\" content=\"Monty 3D frame clamp with sleeves to mount on the Kidevo (Ottobock) and Kiddo (Veldink4kids) wheelchairs with oval frame tubes 50 x 25 mm.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/csmounts.com\/new-csmounts\/product\/m3d-rkl-kidevo-kiddo\/\" \/>\n<meta property=\"og:site_name\" content=\"CS Mounting Systems\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-11T06:15:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/csmounts.com\/new-csmounts\/wp-content\/uploads\/2024\/11\/sitelogo-2.png?fit=585%2C103&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"585\" \/>\n\t<meta property=\"og:image:height\" content=\"103\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/csmounts.com\\\/new-csmounts\\\/product\\\/m3d-rkl-kidevo-kiddo\\\/\",\"url\":\"https:\\\/\\\/csmounts.com\\\/new-csmounts\\\/product\\\/m3d-rkl-kidevo-kiddo\\\/\",\"name\":\"M3D RKL Kidevo\\\/Kiddo - CS Mounting Systems\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/csmounts.com\\\/new-csmounts\\\/#website\"},\"datePublished\":\"2024-12-29T07:38:41+00:00\",\"dateModified\":\"2025-01-11T06:15:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/csmounts.com\\\/new-csmounts\\\/product\\\/m3d-rkl-kidevo-kiddo\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/csmounts.com\\\/new-csmounts\\\/product\\\/m3d-rkl-kidevo-kiddo\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/csmounts.com\\\/new-csmounts\\\/product\\\/m3d-rkl-kidevo-kiddo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/csmounts.com\\\/new-csmounts\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/csmounts.com\\\/new-csmounts\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"M3D RKL Kidevo\\\/Kiddo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/csmounts.com\\\/new-csmounts\\\/#website\",\"url\":\"https:\\\/\\\/csmounts.com\\\/new-csmounts\\\/\",\"name\":\"CS Mounting Systems\",\"description\":\"CS Mounting Systems is the Canadian distributor for Rehadapt\",\"publisher\":{\"@id\":\"https:\\\/\\\/csmounts.com\\\/new-csmounts\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/csmounts.com\\\/new-csmounts\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/csmounts.com\\\/new-csmounts\\\/#organization\",\"name\":\"CS Mounting Systems\",\"url\":\"https:\\\/\\\/csmounts.com\\\/new-csmounts\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/csmounts.com\\\/new-csmounts\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/csmounts.com\\\/new-csmounts\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/sitelogo-2.png?fit=585%2C103&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/csmounts.com\\\/new-csmounts\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/sitelogo-2.png?fit=585%2C103&ssl=1\",\"width\":585,\"height\":103,\"caption\":\"CS Mounting Systems\"},\"image\":{\"@id\":\"https:\\\/\\\/csmounts.com\\\/new-csmounts\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"M3D RKL Kidevo\/Kiddo - CS Mounting Systems","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/csmounts.com\/new-csmounts\/product\/m3d-rkl-kidevo-kiddo\/","og_locale":"en_US","og_type":"article","og_title":"M3D RKL Kidevo\/Kiddo - CS Mounting Systems","og_description":"Monty 3D frame clamp with sleeves to mount on the Kidevo (Ottobock) and Kiddo (Veldink4kids) wheelchairs with oval frame tubes 50 x 25 mm.","og_url":"https:\/\/csmounts.com\/new-csmounts\/product\/m3d-rkl-kidevo-kiddo\/","og_site_name":"CS Mounting Systems","article_modified_time":"2025-01-11T06:15:00+00:00","og_image":[{"width":585,"height":103,"url":"https:\/\/i0.wp.com\/csmounts.com\/new-csmounts\/wp-content\/uploads\/2024\/11\/sitelogo-2.png?fit=585%2C103&ssl=1","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/csmounts.com\/new-csmounts\/product\/m3d-rkl-kidevo-kiddo\/","url":"https:\/\/csmounts.com\/new-csmounts\/product\/m3d-rkl-kidevo-kiddo\/","name":"M3D RKL Kidevo\/Kiddo - CS Mounting Systems","isPartOf":{"@id":"https:\/\/csmounts.com\/new-csmounts\/#website"},"datePublished":"2024-12-29T07:38:41+00:00","dateModified":"2025-01-11T06:15:00+00:00","breadcrumb":{"@id":"https:\/\/csmounts.com\/new-csmounts\/product\/m3d-rkl-kidevo-kiddo\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/csmounts.com\/new-csmounts\/product\/m3d-rkl-kidevo-kiddo\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/csmounts.com\/new-csmounts\/product\/m3d-rkl-kidevo-kiddo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/csmounts.com\/new-csmounts\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/csmounts.com\/new-csmounts\/shop\/"},{"@type":"ListItem","position":3,"name":"M3D RKL Kidevo\/Kiddo"}]},{"@type":"WebSite","@id":"https:\/\/csmounts.com\/new-csmounts\/#website","url":"https:\/\/csmounts.com\/new-csmounts\/","name":"CS Mounting Systems","description":"CS Mounting Systems is the Canadian distributor for Rehadapt","publisher":{"@id":"https:\/\/csmounts.com\/new-csmounts\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/csmounts.com\/new-csmounts\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/csmounts.com\/new-csmounts\/#organization","name":"CS Mounting Systems","url":"https:\/\/csmounts.com\/new-csmounts\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/csmounts.com\/new-csmounts\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/csmounts.com\/new-csmounts\/wp-content\/uploads\/2024\/11\/sitelogo-2.png?fit=585%2C103&ssl=1","contentUrl":"https:\/\/i0.wp.com\/csmounts.com\/new-csmounts\/wp-content\/uploads\/2024\/11\/sitelogo-2.png?fit=585%2C103&ssl=1","width":585,"height":103,"caption":"CS Mounting Systems"},"image":{"@id":"https:\/\/csmounts.com\/new-csmounts\/#\/schema\/logo\/image\/"}}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/csmounts.com\/new-csmounts\/wp-json\/wp\/v2\/product\/500","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/csmounts.com\/new-csmounts\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/csmounts.com\/new-csmounts\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/csmounts.com\/new-csmounts\/wp-json\/wp\/v2\/comments?post=500"}],"wp:attachment":[{"href":"https:\/\/csmounts.com\/new-csmounts\/wp-json\/wp\/v2\/media?parent=500"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/csmounts.com\/new-csmounts\/wp-json\/wp\/v2\/product_brand?post=500"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/csmounts.com\/new-csmounts\/wp-json\/wp\/v2\/product_cat?post=500"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/csmounts.com\/new-csmounts\/wp-json\/wp\/v2\/product_tag?post=500"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}